{"id":845,"count":4,"description":"","link":"https:\/\/villadianella.it\/en\/tag\/esperienze-enogastronomiche-toscana-en","name":"esperienze enogastronomiche Toscana","slug":"esperienze-enogastronomiche-toscana-en","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/villadianella.it\/en\/wp-json\/wp\/v2\/tags\/845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/villadianella.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/villadianella.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/villadianella.it\/en\/wp-json\/wp\/v2\/posts?tags=845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}